{"id":513,"count":0,"description":"Las balanzas Dibal son una apuesta segura cuando se busca precisi\u00f3n, fiabilidad y durabilidad en el pesaje profesional. Fabricadas con criterios industriales y pensadas para el ritmo real del comercio, responden igual de bien en un peque\u00f1o establecimiento que en entornos con un gran volumen de ventas.\r\n\r\nLa gama Dibal abarca desde balanzas de pesaje sencillas hasta soluciones PC avanzadas con pantalla t\u00e1ctil, impresi\u00f3n de etiquetas e integraci\u00f3n con sistemas de gesti\u00f3n y TPV. Todo est\u00e1 dise\u00f1ado para que el trabajo sea \u00e1gil, intuitivo y sin errores, tanto para el vendedor como para el cliente.\r\n\r\nOtro punto clave es la adaptaci\u00f3n normativa. Las balanzas Dibal est\u00e1n preparadas para cumplir con Verifactu, facilitando la generaci\u00f3n y transmisi\u00f3n de datos seg\u00fan la normativa fiscal vigente y evitando futuros problemas de adecuaci\u00f3n. Tecnolog\u00eda preparada no solo para hoy, sino tambi\u00e9n para lo que viene.\r\n\r\nRobustez, precisi\u00f3n constante y evoluci\u00f3n tecnol\u00f3gica. Eso es lo que ofrece Dibal: balanzas pensadas para trabajar durante muchos a\u00f1os, con soporte, actualizaciones y la tranquilidad de hacer las cosas bien desde el primer d\u00eda.\r\n","link":"https:\/\/servifibal.cat\/es\/cat-prod\/balanzas-dibal\/","name":"Balanzas Dibal","slug":"balanzas-dibal","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Balanzas Dibal archivos - Servifibal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/servifibal.cat\/es\/cat-prod\/balanzas-dibal\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Balanzas Dibal archivos - Servifibal\" \/>\n<meta property=\"og:description\" content=\"Las balanzas Dibal son una apuesta segura cuando se busca precisi\u00f3n, fiabilidad y durabilidad en el pesaje profesional. Fabricadas con criterios industriales y pensadas para el ritmo real del comercio, responden igual de bien en un peque\u00f1o establecimiento que en entornos con un gran volumen de ventas. La gama Dibal abarca desde balanzas de pesaje sencillas hasta soluciones PC avanzadas con pantalla t\u00e1ctil, impresi\u00f3n de etiquetas e integraci\u00f3n con sistemas de gesti\u00f3n y TPV. Todo est\u00e1 dise\u00f1ado para que el trabajo sea \u00e1gil, intuitivo y sin errores, tanto para el vendedor como para el cliente. Otro punto clave es la adaptaci\u00f3n normativa. Las balanzas Dibal est\u00e1n preparadas para cumplir con Verifactu, facilitando la generaci\u00f3n y transmisi\u00f3n de datos seg\u00fan la normativa fiscal vigente y evitando futuros problemas de adecuaci\u00f3n. Tecnolog\u00eda preparada no solo para hoy, sino tambi\u00e9n para lo que viene. Robustez, precisi\u00f3n constante y evoluci\u00f3n tecnol\u00f3gica. Eso es lo que ofrece Dibal: balanzas pensadas para trabajar durante muchos a\u00f1os, con soporte, actualizaciones y la tranquilidad de hacer las cosas bien desde el primer d\u00eda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/servifibal.cat\/es\/cat-prod\/balanzas-dibal\/\" \/>\n<meta property=\"og:site_name\" content=\"Servifibal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/servifibal.cat\\\/es\\\/cat-prod\\\/balanzas-dibal\\\/\",\"url\":\"https:\\\/\\\/servifibal.cat\\\/es\\\/cat-prod\\\/balanzas-dibal\\\/\",\"name\":\"Balanzas Dibal archivos - Servifibal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/servifibal.cat\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/servifibal.cat\\\/es\\\/cat-prod\\\/balanzas-dibal\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/servifibal.cat\\\/es\\\/cat-prod\\\/balanzas-dibal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/servifibal.cat\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Balanzas Dibal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/servifibal.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/servifibal.cat\\\/es\\\/\",\"name\":\"Servifibal\",\"description\":\"Solucions per al petit comer\u00e7\",\"publisher\":{\"@id\":\"https:\\\/\\\/servifibal.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/servifibal.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/servifibal.cat\\\/es\\\/#organization\",\"name\":\"Servifibal\",\"url\":\"https:\\\/\\\/servifibal.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/servifibal.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/servifibal.cat\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/00-Logo-nou-blanc.png\",\"contentUrl\":\"https:\\\/\\\/servifibal.cat\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/00-Logo-nou-blanc.png\",\"width\":176,\"height\":38,\"caption\":\"Servifibal\"},\"image\":{\"@id\":\"https:\\\/\\\/servifibal.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Balanzas Dibal archivos - Servifibal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/servifibal.cat\/es\/cat-prod\/balanzas-dibal\/","og_locale":"es_ES","og_type":"article","og_title":"Balanzas Dibal archivos - Servifibal","og_description":"Las balanzas Dibal son una apuesta segura cuando se busca precisi\u00f3n, fiabilidad y durabilidad en el pesaje profesional. Fabricadas con criterios industriales y pensadas para el ritmo real del comercio, responden igual de bien en un peque\u00f1o establecimiento que en entornos con un gran volumen de ventas. La gama Dibal abarca desde balanzas de pesaje sencillas hasta soluciones PC avanzadas con pantalla t\u00e1ctil, impresi\u00f3n de etiquetas e integraci\u00f3n con sistemas de gesti\u00f3n y TPV. Todo est\u00e1 dise\u00f1ado para que el trabajo sea \u00e1gil, intuitivo y sin errores, tanto para el vendedor como para el cliente. Otro punto clave es la adaptaci\u00f3n normativa. Las balanzas Dibal est\u00e1n preparadas para cumplir con Verifactu, facilitando la generaci\u00f3n y transmisi\u00f3n de datos seg\u00fan la normativa fiscal vigente y evitando futuros problemas de adecuaci\u00f3n. Tecnolog\u00eda preparada no solo para hoy, sino tambi\u00e9n para lo que viene. Robustez, precisi\u00f3n constante y evoluci\u00f3n tecnol\u00f3gica. Eso es lo que ofrece Dibal: balanzas pensadas para trabajar durante muchos a\u00f1os, con soporte, actualizaciones y la tranquilidad de hacer las cosas bien desde el primer d\u00eda.","og_url":"https:\/\/servifibal.cat\/es\/cat-prod\/balanzas-dibal\/","og_site_name":"Servifibal","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/servifibal.cat\/es\/cat-prod\/balanzas-dibal\/","url":"https:\/\/servifibal.cat\/es\/cat-prod\/balanzas-dibal\/","name":"Balanzas Dibal archivos - Servifibal","isPartOf":{"@id":"https:\/\/servifibal.cat\/es\/#website"},"breadcrumb":{"@id":"https:\/\/servifibal.cat\/es\/cat-prod\/balanzas-dibal\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/servifibal.cat\/es\/cat-prod\/balanzas-dibal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/servifibal.cat\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Balanzas Dibal"}]},{"@type":"WebSite","@id":"https:\/\/servifibal.cat\/es\/#website","url":"https:\/\/servifibal.cat\/es\/","name":"Servifibal","description":"Solucions per al petit comer\u00e7","publisher":{"@id":"https:\/\/servifibal.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/servifibal.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/servifibal.cat\/es\/#organization","name":"Servifibal","url":"https:\/\/servifibal.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/servifibal.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/servifibal.cat\/wp-content\/uploads\/2025\/11\/00-Logo-nou-blanc.png","contentUrl":"https:\/\/servifibal.cat\/wp-content\/uploads\/2025\/11\/00-Logo-nou-blanc.png","width":176,"height":38,"caption":"Servifibal"},"image":{"@id":"https:\/\/servifibal.cat\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/servifibal.cat\/es\/wp-json\/wp\/v2\/product_cat\/513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/servifibal.cat\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/servifibal.cat\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/servifibal.cat\/es\/wp-json\/wp\/v2\/product?product_cat=513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}